{"id":62,"date":"2021-09-02T18:14:57","date_gmt":"2021-09-02T18:14:57","guid":{"rendered":"https:\/\/vitalmeaning.com\/?p=62"},"modified":"2021-09-04T07:29:16","modified_gmt":"2021-09-04T07:29:16","slug":"la-herramienta-de-procesamiento-emocional-basada-en-las-ensenanzas-de-thais-gibson","status":"publish","type":"post","link":"https:\/\/vitalmeaning.com\/es\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/","title":{"rendered":"La herramienta de procesamiento emocional basada en las ense\u00f1anzas de Thais Gibson"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El prop\u00f3sito de este proceso (herramienta de procesamiento emocional) es ser capaz de manejar las emociones intensas y los procesos emocionalmente molestos por ti mismo de una manera constructiva. Identificar las necesidades reales en el fondo de tus emociones, y eliminar el dolor de las historias que te cuentas a ti mismo sobre esto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He preparado un resumen del proceso, que tambi\u00e9n forma parte de una plantilla descargable en PDF para que puedas hacer el proceso por tu cuenta:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2021\/09\/Emotional-processing-Template.pdf\">plantilla de herramienta de procesamiento emocional (PDF)<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n he proporcionado un ejemplo de una corrida reciente que he hecho (para prop\u00f3sitos de demostraci\u00f3n, pero un incidente real) donde he compensado mis emociones e identificado mis necesidades, y he llegado a interesantes percepciones. \u00a1Sucede cada vez que se ejecuta este proceso!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2021\/09\/Emotional-processing-example-Trigger-September-2021.pdf\">ejemplo de aplicaci\u00f3n de la herramienta de procesamiento emocional (PDF)<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lo \u00fanico que no puedo proporcionarte aqu\u00ed es la lista de emociones que utilizo como herramienta de ayuda para llevar a cabo este proceso. Probablemente puedes utilizar cualquier lista razonablemente corta de emociones que encuentres en Internet para guiarte, o incluso simplemente escribir las emociones que sientes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O incluso mejor, <a href=\"https:\/\/university.personaldevelopmentschool.com\/\">unirse a la escuela de desarrollo personal de Thais<\/a> para obtener este PDF como parte de muchos de sus cursos. Recomiendo encarecidamente su escuela, y me he ahorrado un mont\u00f3n de dolor y he sido capaz de volver a conectar con una mujer evasiva desde\u00f1osa gracias a las ense\u00f1anzas de Thais.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De todas formas, vamos con la herramienta de procesamiento emocional \ud83d\ude42 . <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Este proceso es <a href=\"https:\/\/university.personaldevelopmentschool.com\/\">basado en el trabajo de la encantadora Thais Gibson<\/a>(con algunas modificaciones por mi parte - ella amablemente me dio permiso para publicar mi versi\u00f3n).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n proporciono un ejemplo completo de esto, en el que he repasado un encuentro reciente con un agente de televentas que me result\u00f3 molesto, para que puedas ver c\u00f3mo funciona en la pr\u00e1ctica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo personalmente tengo un archivo de Word por mes, y por lo general una de esas sesiones que corro a trav\u00e9s de cada par de d\u00edas, cuando algo realmente me molesta, cuando me siento abajo - en cualquier situaci\u00f3n emocionalmente estresante realmente. Es bueno saber que la mayor\u00eda de los d\u00edas no hay m\u00e1s de una \ud83d\ude42 y que mejora con el tiempo - s\u00f3lo practica esta herramienta, y eliminar\u00e1s mucho dolor de tu vida, \u00a1lo prometo!<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Antes de empezar<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos consejos clave antes de empezar:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>pon un temporizador de cuenta atr\u00e1s de 20 minutos en tu smartphone<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es <strong>muy<\/strong> es importante - de lo contrario, podr\u00edas encontrar que el proceso toma demasiado tiempo, y lo pospondr\u00e1s, porque \"no tienes tiempo ahora\". Pero es importante hacerlo con regularidad, aunque no lo hagas a la perfecci\u00f3n: 20 minutos al d\u00eda, o 20 minutos por cada incidente molesto, te ahorrar\u00e1n MUCHO tiempo de sufrimiento y desconcentraci\u00f3n, de obsesi\u00f3n por la situaci\u00f3n, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conf\u00eda en m\u00ed... <strong>todo el mundo<\/strong> tiene 20 minutos. Y eso es todo lo que necesitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pon el temporizador y vete a trabajar en cuanto est\u00e9s libre y puedas hacerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hazlo por ti mismo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>asegurarse de que est\u00e1 solo y puede ser honesto y volcar en el papel todo lo que le pesa, emocionalmente hablando<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vas a poner por escrito (con suerte) muchos de tus pensamientos internos, preocupaciones, etc. Se trata de algo muy privado y, por lo tanto, debes estar solo, a salvo de interrupciones.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>ponte c\u00f3modo - trae t\u00e9 \/ chocolate \/ una manta acogedora<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Te recomiendo que te pongas lo m\u00e1s c\u00f3modo posible para este trabajo, para que realmente lo disfrutes en alg\u00fan nivel. Lo est\u00e1s haciendo por tu alma, y para quitarle el sufrimiento. Este es un trabajo muy noble, y merece ser celebrado con un poco de comodidad a su alrededor.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>hazlo con regularidad, convi\u00e9rtelo en tu proceso habitual cuando est\u00e9s molesto<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Con frecuencia, se obtendr\u00e1n muchas y buenas percepciones. Estar\u00e1s m\u00e1s tranquilo en tus interacciones con otras personas. Este es un ciclo virtuoso que estamos iniciando aqu\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tiempo ser\u00e1 bien invertido, aunque a veces parezca dif\u00edcil sacarlo adelante. De hecho, dejar\u00e9 de lado otras tareas y cosas que quieren los clientes, etc. - porque necesito estar en un estado emocional tranquilo para trabajar, y esta herramienta es la que me lo proporciona (\u00a1lo que ayuda enormemente, cada vez!).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>(Paso 0) Situaci\u00f3n:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Describa la situaci\u00f3n que le ha molestado, intente ser lo m\u00e1s neutral posible y d\u00e9 s\u00f3lo hechos, no interpretaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las interpretaciones (\"significado\" \/ alias \"tu historia\") vendr\u00e1n despu\u00e9s, no te preocupes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto tambi\u00e9n es interesante por razones hist\u00f3ricas, as\u00ed que podr\u00e1s volver atr\u00e1s y ver qu\u00e9 eventos te molestaban en el pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te prometo que si sigues este proceso, te convertir\u00e1s en una persona mucho m\u00e1s tranquila y equilibrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hay que repetirlo muchas veces para que se convierta en algo autom\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merece la pena: eliminar\u00e1 MUCHO dolor de tu vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(He incluido este paso yo mismo, tambi\u00e9n para centrar mis pensamientos en la situaci\u00f3n - Thais no lo tiene, por lo tanto es mi paso zeroth)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>(Paso 1) Sentimientos:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Escribe una lista de los sentimientos que sientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prefiero escribir una lista, en lugar de tener un \"sentimiento singular\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizo el folleto de emociones de Thais Gibson y repaso toda la lista, para ver si algo de lo que hay coincide conmigo. (Recomiendo encarecidamente que te unas a la escuela de desarrollo personal de Thais, para que puedas conseguir el folleto, y un mont\u00f3n de otros consejos sobre c\u00f3mo crecer y tener relaciones saludables y pr\u00f3speras).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pondr\u00e9 las emociones que son especialmente fuertes para m\u00ed en <strong>negrita<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&nbsp;(Paso 2) Loc(aci\u00f3n):<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Escuche su cuerpo e identifique d\u00f3nde siente que se localizan las emociones; por ejemplo, siento muchas emociones en mi vientre. Intenta describir c\u00f3mo se siente la emoci\u00f3n en esa zona concreta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thais dice que este trabajo ya es un paso importante para calmarse y salir del estado de hiperactividad, ya que est\u00e1s cambiando tu atenci\u00f3n. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anota estas localizaciones corporales. Thais dice que las emociones son s\u00f3lo sentimientos en tu cuerpo, y nada m\u00e1s temible que eso. Esta parte del proceso te ayudar\u00e1 a familiarizarte con estos sentimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con frecuencia cierro los ojos mientras hago esta exploraci\u00f3n del cuerpo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>(Paso 3) Significado:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el paso en el que puedes volcar en tu procesador de textos todo lo que te molesta de esta situaci\u00f3n, de este encuentro con esta persona en particular, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el momento de escribir realmente lo que est\u00e1s pensando actualmente, por ejemplo, creo que tambi\u00e9n es bueno volcar las cosas que incluyen palabras malsonantes, etc. - para que est\u00e9n fuera de tu sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dejar\u00e1s de obsesionarte tanto con ellas, ya que est\u00e1n escritas y no se pueden olvidar de esta manera \ud83d\ude42 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n un consejo profesional importante aqu\u00ed: En el siguiente paso, en el que vas a compensar, no hagas una \"visi\u00f3n equilibrada con pros y contras\". Si se te ocurren sentimientos o creencias negativas adicionales, pon <strong>aqu\u00ed<\/strong> (en la parte del significado) al final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera tambi\u00e9n se ordenar\u00e1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>(Paso 4) \"\u00bfPuedo 100 % saber?\" (compensaci\u00f3n emocional)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Copie frase por frase y repase cada frase individualmente cuestion\u00e1ndola, anteponiendo la frase con \"<strong>Puedo 100 % saber que ... <\/strong><em>(pegar aqu\u00ed la frase del significado)<\/em>\". El objetivo no es hacer \"todas las frases\" sino contrarrestar tu estado de activaci\u00f3n emocional, una vez que te sientas m\u00e1s tranquilo (o de hecho hayas hecho todas las frases) pasa al siguiente paso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es el n\u00facleo del proceso, y lo que te ayudar\u00e1 a calmarte (antes de que puedas llegar a la necesidad real, que ahora mismo est\u00e1 superpuesta por tus historias dolorosas). Te ayudar\u00e1 a actuar desde la calma, en lugar de reaccionar desde el dolor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que hago es escribir vi\u00f1etas con los pensamientos que me vienen a la cabeza sobre por qu\u00e9 posiblemente mis historias son s\u00f3lo eso... <strong>historias<\/strong>. Por qu\u00e9 no debo tomarme como algo personal el comportamiento abrasivo de otras personas, ... cualquier punto que se me ocurra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n profundizar\u00e9 en los puntos secundarios que me llamen la atenci\u00f3n, por ejemplo, las tangentes de una idea concreta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se me ocurrir\u00e1n ejemplos de mi propio pasado, en los que he actuado de forma similar por una raz\u00f3n inocente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voy a cuestionar mis propias expectativas de la situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es especialmente importante cuestionar las afirmaciones globales (pensamiento en blanco y negro), por ejemplo, \"este error me arruinar\u00e1\" o \"no se puede confiar en ellos\" o \"a esta persona no le importo en absoluto\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Practicar con esto te ayudar\u00e1 a tener mejores ideas en el futuro, y tambi\u00e9n te ayudar\u00e1 a empezar a cuestionar y compensar en tiempo real, cuando el incidente ocurra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes encontrar un buen ejemplo de lo que escribo en una situaci\u00f3n as\u00ed en mi archivo de ejemplos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor parte del tiempo que dediques al procesamiento emocional debes pasarlo aqu\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ten en cuenta estos puntos importantes cuando lo hagas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El objetivo no es encontrar \"justicia\" aqu\u00ed - el objetivo es llegar a ser emocionalmente m\u00e1s tranquilo, y ver la situaci\u00f3n por lo que es - para entonces ser capaz de ver cu\u00e1les son sus necesidades reales y c\u00f3mo abordarlas.<ul><li><strong>Por lo tanto, no intentes \"equilibrar\" y encontrar \"pruebas negativas\"<\/strong> - si surgen dudas adicionales, ponlas en \"significado\". Tienes un procesador de textos, as\u00ed que \u00fasalo para editar en los lugares adecuados.<\/li><\/ul><\/li><li>Lo haces por ti, no por la otra persona. Lo haces para eliminar el dolor innecesario de tu vida. Puede que la otra persona se haya comportado de una manera muy injusta - pero esta es tu vida, tus emociones, y no deber\u00edas castigarte extra y encima de su comportamiento con historias dolorosas, sobre c\u00f3mo no eres X, no eres Y, etc. - haz esta herramienta, quita el dolor, considera lo que necesitas, y toma medidas (ver los dos pasos siguientes)<\/li><li><strong>S\u00e9 honesto en los puntos positivos y en los ejemplos que aportes<\/strong>. Si una situaci\u00f3n es realmente mala, no te mientas a ti mismo - no funcionar\u00e1 de todos modos. Aqu\u00ed se trata de encontrar la duda HONESTA sobre las historias (que a menudo son exageraciones y pensamientos en blanco y negro), \u00a1no de tratar de enga\u00f1arte a ti mismo! (\u00a1Importante para confiar en ti mismo es ser honesto contigo mismo!)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tengo que admitir sinceramente que a menudo sigo en esta parte, aunque suene la alarma del smartphone, porque siento que a\u00fan no estoy del todo compensado, pero que me siento bien y el dolor se rebaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s soy obsesiva, y quiero terminar las tareas que empiezo \ud83d\ude42 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero incluso un poco de esto te ayudar\u00e1, \u00a1lo prometo! Haga esto, intente esto durante 30 d\u00edas, intente hacerlo todos los d\u00edas, y habr\u00e1 resultados maravillosos en menos reactividad emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cuando me sienta completamente compensado, pasar\u00e9 al siguiente paso - no es necesario pasar por TODAS las frases que has puesto en sentido. Recuerde, el prop\u00f3sito de este paso es reducir su dolor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se siente maravilloso tener una herramienta como esta, que no adormece el dolor, sino que cambia tu perspectiva de las cosas \ud83d\ude42 . <em>&nbsp;<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>(Paso 5a) \"\u00bfQu\u00e9 necesito de esta persona?\"<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esto tambi\u00e9n es una desviaci\u00f3n de la herramienta original de Thais que me pareci\u00f3 \u00fatil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber lo que necesitas en esta situaci\u00f3n, escribe \"\u00bfQu\u00e9 necesito de X en esta situaci\u00f3n?\", y luego enumera lo que te gustar\u00eda que hicieran \/ cambiaran \/ ...<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerda que s\u00f3lo debes realizar este paso despu\u00e9s de haber compensado tus historias dolorosas. De lo contrario, puede que no llegues a las verdaderas necesidades subyacentes, sino que act\u00faes desde el dolor (por ejemplo, \"no quiero volver a ver a esta persona nunca m\u00e1s, ...\")<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&nbsp;(Paso 5b) \"\u00bfC\u00f3mo puedo d\u00e1rmelo a m\u00ed mismo?\"<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El paso 5a era s\u00f3lo una preparaci\u00f3n - si ves maneras de que la otra persona pueda darte eso, est\u00e1 bien. Pero si puedes d\u00e1rtelo a ti mismo, est\u00e1 muy bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que me lo he formulado como \"C\u00f3mo puedo d\u00e1rmelo a m\u00ed mismo\", y hago una lluvia de ideas de lo que podr\u00eda hacer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto te va a calmar a\u00fan m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El siguiente paso, por supuesto, es aplicar estas estrategias \ud83d\ude42 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buena suerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me parece que llevar a cabo este proceso me ha convertido en una persona mucho m\u00e1s tranquila a lo largo del a\u00f1o y medio que llevo haci\u00e9ndolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estoy profundamente agradecido a <a href=\"https:\/\/university.personaldevelopmentschool.com\/\">Thais Gibson<\/a> por compartir el proceso con nosotros en <a href=\"https:\/\/university.personaldevelopmentschool.com\/\">su escuela<\/a> y en sus v\u00eddeos de YouTube. Me ha quitado mucho dolor de mi vida, y es maravilloso saber que siempre puedo recurrir a este proceso cuando estoy molesta.<\/p>\n\n\n\n<p><span style=\"background-color: #ffff00;\"><strong>Hazlo<\/strong>. Deja de leer sobre ello \ud83d\ude42 .<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>The purpose of this process (emotional processing tool) is to be able to handle intense emotions &amp; emotionally upsetting processes on your own in a constructive way. To identify the actual needs at the bottom of your emotions, and to remove pain from stories you tell yourself about this. I&#8217;ve prepared a run-down through the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[],"class_list":["post-62","post","type-post","status-publish","format-standard","hentry","category-tools-for-emotional-work"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The emotional processing tool as based on Thais Gibson&#039;s teachings - VitalMeaning<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vitalmeaning.com\/es\/la-herramienta-de-procesamiento-emocional-basada-en-las-ensenanzas-de-thais-gibson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The emotional processing tool as based on Thais Gibson&#039;s teachings - VitalMeaning\" \/>\n<meta property=\"og:description\" content=\"The purpose of this process (emotional processing tool) is to be able to handle intense emotions &amp; emotionally upsetting processes on your own in a constructive way. To identify the actual needs at the bottom of your emotions, and to remove pain from stories you tell yourself about this. I&#8217;ve prepared a run-down through the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vitalmeaning.com\/es\/la-herramienta-de-procesamiento-emocional-basada-en-las-ensenanzas-de-thais-gibson\/\" \/>\n<meta property=\"og:site_name\" content=\"VitalMeaning\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-02T18:14:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-04T07:29:16+00:00\" \/>\n<meta name=\"author\" content=\"Max\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Max\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/\"},\"author\":{\"name\":\"Max\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\"},\"headline\":\"The emotional processing tool as based on Thais Gibson&#8217;s teachings\",\"datePublished\":\"2021-09-02T18:14:57+00:00\",\"dateModified\":\"2021-09-04T07:29:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/\"},\"wordCount\":2167,\"commentCount\":5,\"articleSection\":[\"tools for emotional work\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/\",\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/\",\"name\":\"The emotional processing tool as based on Thais Gibson's teachings - VitalMeaning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#website\"},\"datePublished\":\"2021-09-02T18:14:57+00:00\",\"dateModified\":\"2021-09-04T07:29:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vitalmeaning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The emotional processing tool as based on Thais Gibson&#8217;s teachings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#website\",\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/\",\"name\":\"VitalMeaning\",\"description\":\"my self development journey\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vitalmeaning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\",\"name\":\"Max\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"caption\":\"Max\"},\"description\":\"I am an entrepreneur with an eclectic background. Currently into Raspberry Pi, Artificial Intelligence, and Personal Development. A big fan of Thais Gibson and her YouTube channel &amp; school :-)\",\"sameAs\":[\"https:\\\/\\\/pi3g.com\"],\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/es\\\/author\\\/max\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La herramienta de procesamiento emocional basada en las ense\u00f1anzas de Thais Gibson - VitalMeaning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vitalmeaning.com\/es\/la-herramienta-de-procesamiento-emocional-basada-en-las-ensenanzas-de-thais-gibson\/","og_locale":"es_ES","og_type":"article","og_title":"The emotional processing tool as based on Thais Gibson's teachings - VitalMeaning","og_description":"The purpose of this process (emotional processing tool) is to be able to handle intense emotions &amp; emotionally upsetting processes on your own in a constructive way. To identify the actual needs at the bottom of your emotions, and to remove pain from stories you tell yourself about this. I&#8217;ve prepared a run-down through the [&hellip;]","og_url":"https:\/\/vitalmeaning.com\/es\/la-herramienta-de-procesamiento-emocional-basada-en-las-ensenanzas-de-thais-gibson\/","og_site_name":"VitalMeaning","article_published_time":"2021-09-02T18:14:57+00:00","article_modified_time":"2021-09-04T07:29:16+00:00","author":"Max","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Max","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/#article","isPartOf":{"@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/"},"author":{"name":"Max","@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff"},"headline":"The emotional processing tool as based on Thais Gibson&#8217;s teachings","datePublished":"2021-09-02T18:14:57+00:00","dateModified":"2021-09-04T07:29:16+00:00","mainEntityOfPage":{"@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/"},"wordCount":2167,"commentCount":5,"articleSection":["tools for emotional work"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/","url":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/","name":"La herramienta de procesamiento emocional basada en las ense\u00f1anzas de Thais Gibson - VitalMeaning","isPartOf":{"@id":"https:\/\/vitalmeaning.com\/#website"},"datePublished":"2021-09-02T18:14:57+00:00","dateModified":"2021-09-04T07:29:16+00:00","author":{"@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff"},"breadcrumb":{"@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vitalmeaning.com\/the-emotional-processing-tool-as-based-on-thais-gibsons-teachings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vitalmeaning.com\/"},{"@type":"ListItem","position":2,"name":"The emotional processing tool as based on Thais Gibson&#8217;s teachings"}]},{"@type":"WebSite","@id":"https:\/\/vitalmeaning.com\/#website","url":"https:\/\/vitalmeaning.com\/","name":"VitalMeaning","description":"mi viaje de autodesarrollo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vitalmeaning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff","name":"Max","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","caption":"Max"},"description":"Soy un emprendedor con una formaci\u00f3n ecl\u00e9ctica. Actualmente me dedico a la Raspberry Pi, la inteligencia artificial y el desarrollo personal. Un gran fan de Thais Gibson y su canal de YouTube y la escuela :-)","sameAs":["https:\/\/pi3g.com"],"url":"https:\/\/vitalmeaning.com\/es\/author\/max\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Max","author_link":"https:\/\/vitalmeaning.com\/es\/author\/max\/"},"uagb_comment_info":5,"uagb_excerpt":"The purpose of this process (emotional processing tool) is to be able to handle intense emotions &amp; emotionally upsetting processes on your own in a constructive way. To identify the actual needs at the bottom of your emotions, and to remove pain from stories you tell yourself about this. I&#8217;ve prepared a run-down through the&hellip;","_links":{"self":[{"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/posts\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":7,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/posts\/62\/revisions"}],"predecessor-version":[{"id":81,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/posts\/62\/revisions\/81"}],"wp:attachment":[{"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/media?parent=62"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/categories?post=62"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vitalmeaning.com\/es\/wp-json\/wp\/v2\/tags?post=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}