{"id":336,"date":"2023-03-05T06:21:56","date_gmt":"2023-03-05T06:21:56","guid":{"rendered":"https:\/\/vitalmeaning.com\/?p=336"},"modified":"2023-03-05T06:21:57","modified_gmt":"2023-03-05T06:21:57","slug":"ne-pas-payer-les-prix-que-dautres-devraient-payer","status":"publish","type":"post","link":"https:\/\/vitalmeaning.com\/fr\/dont-pay-prices-other-people-should-be-paying\/","title":{"rendered":"Ne payez pas les prix que d'autres devraient payer."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Lorsque vous allez faire des courses avec vos amis, payez-vous leurs courses ? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peut-\u00eatre de temps en temps, mais pas tout le temps, non ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parfois, nous finissons par \"payer les courses\" de personnes importantes dans nos vies. Et une personne qui ne paie pas elle-m\u00eame les courses ne percevra pas leur valeur de mani\u00e8re aussi directe et imm\u00e9diate que si elle les payait - c'est tout simplement la nature humaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cet article, je fais r\u00e9f\u00e9rence \u00e0 la <a href=\"https:\/\/vitalmeaning.com\/fr\/une-video-importante-sur-les-comportements-dautodefense\/\">comportement autodestructeur<\/a> (SDB), <a href=\"https:\/\/vitalmeaning.com\/fr\/une-video-importante-sur-les-comportements-dautodefense\/\">pour laquelle vous pouvez trouver une excellente vid\u00e9o ici<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En bref, le comportement autodestructeur est aliment\u00e9 par les mauvais choix (\"tourner \u00e0 gauche au lieu de tourner \u00e0 droite\"), qui \u00e0 leur tour sont aliment\u00e9s par <strong>peurs mythiques<\/strong> de faire les bons choix (\"tourner \u00e0 droite\"). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, si vous avez peur d'\u00eatre vuln\u00e9rable et d'aborder les probl\u00e8mes avec votre partenaire - et que vous pr\u00e9f\u00e9rez les balayer sous le tapis, les probl\u00e8mes et le ressentiment vont s'accumuler. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou, autre exemple, si au lieu de discuter de ces probl\u00e8mes ou de consulter un th\u00e9rapeute \u00e0 ce sujet, vous vous autom\u00e9dicamentez avec de l'alcool, vous risquez d'avoir des dommages au foie - et peut-\u00eatre aussi des probl\u00e8mes sociaux, des probl\u00e8mes au travail, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le cadre SDB explique que des choses n\u00e9gatives se produisent lorsque nous faisons syst\u00e9matiquement les mauvais choix. Rappelez-vous, nous faisons les mauvais choix par autopictoire - parce que nous avons des peurs irrationnelles et mythiques (bas\u00e9es sur des exp\u00e9riences r\u00e9elles !) qui nous emp\u00eachent de faire le bon choix. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un bon choix, encore une fois, serait par exemple d'arr\u00eater de boire pour se sentir mieux, et de parler plut\u00f4t de vos probl\u00e8mes avec un th\u00e9rapeute, ou votre partenaire. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puisque ce bon choix est bloqu\u00e9 par la peur mythique (par exemple, \"le partenaire va me rejeter \/ se moquer de moi \/ ne m'entendra pas et cela fera encore plus mal\"), nous ferons les mauvais choix. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces choix auront des cons\u00e9quences n\u00e9gatives - qui sont appel\u00e9es \"prix\" dans le cadre des PSD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J'ai \u00e9crit un billet sur <a href=\"https:\/\/vitalmeaning.com\/fr\/comportement-dautodefense-illustre\/\">comment cela se passe dans une situation de rencontre ici<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que personne qui pratique les PSD - par exemple la consommation d'alcool - vous payez beaucoup de prix.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Des partenaires qui paient les prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mais vous ne serez pas le seul \u00e0 en payer le prix. Votre cercle social proche, vos partenaires romantiques en paieront aussi le prix, s'ils choisissent de rester avec vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, dans le cas de l'alcool, votre partenaire devra faire face \u00e0 votre gueule de bois, voire \u00e0 votre humeur irritable. Bien s\u00fbr, il y aura moins d'argent disponible pour faire fonctionner le m\u00e9nage, car l'alcool n'est pas vraiment une boisson bon march\u00e9. De plus, dans certaines situations, vous ne serez pas fiable, vous pourrez mettre la famille en danger (conduite en \u00e9tat d'ivresse, etc.) ou vous pourrez g\u00eaner votre partenaire dans un groupe social. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laissons de c\u00f4t\u00e9 l'exemple de l'alcool pour un moment. Discutons des styles d'attachement craintifs et \u00e9vitants qui ne s'engagent pas pleinement. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates amoureux d'une personne qui a un style d'attachement \u00e9vitant et craintif, mais qui vous repousse sans cesse lorsque vous vous approchez, <strong>vous, en tant que partenaire<\/strong>J'ai aussi un probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous payez le prix de votre partenaire craintif et \u00e9vitant. Il se rend donc encore moins compte que son comportement est nuisible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous payez leur facture d'\u00e9picerie, alors qu'ils gaspillent ces pr\u00e9cieuses denr\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne pas avoir de limites solides pour les prix des autres (par exemple aussi un comportement abusif - qui provient encore une fois des peurs mythiques d'\u00eatre vuln\u00e9rable - mais le d\u00e9sir d'\u00eatre le tyran, toujours \"le plus fort\") vous conduira \u00e0 \u00eatre coinc\u00e9 dans la situation avec eux, et rien ne changera. Parce qu'ils sont \"rigidement\" coinc\u00e9s dans ce comportement, c'est-\u00e0-dire jusqu'\u00e0 ce que quelque chose se produise - jusqu'\u00e0 ce qu'ils ressentent la douleur de mani\u00e8re suffisamment aigu\u00eb pour que le SDB finisse par craquer et qu'ils r\u00e9alisent ce qu'ils ont fait. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De pr\u00e9cieuses ann\u00e9es de vie gaspill\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">J'ai moi-m\u00eame pay\u00e9 le prix d'une femme, N., qui n'a cess\u00e9 de me repousser et de se d\u00e9sengager de moi. D'une certaine mani\u00e8re, c'\u00e9tait aussi un comportement autodestructeur de ma part - courir apr\u00e8s une femme \u00e9motionnellement indisponible. Cinq ann\u00e9es \"g\u00e2ch\u00e9es\" (j'en ai retir\u00e9 beaucoup de d\u00e9veloppement personnel). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans mon cas, je lui trouvais des excuses, je continuais \u00e0 m'engager avec elle, au lieu de m'\u00e9loigner d'elle pour de bon. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son comportement exige un prix \u00e0 payer - le d\u00e9sengagement des partenaires romantiques potentiels. Ce comportement est probablement CON\u00c7U dans ce but. Si vous continuez \u00e0 persister et \u00e0 payer son prix - c'est-\u00e0-dire \u00e0 \u00eatre \u00e9motionnellement d\u00e9sempar\u00e9 et stress\u00e9, tout en gardant votre d\u00e9tresse loin d'elle, elle intensifiera ses comportements jusqu'\u00e0 ce qu'ils atteignent leur but, \u00e0 savoir vous \u00e9loigner pour de bon. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les humains sont tr\u00e8s intelligents pour ex\u00e9cuter leur programmation subconsciente, vous voyez. C'est comme un missile \u00e0 t\u00eate chercheuse, jusqu'\u00e0 ce que son but soit atteint, il continuera \u00e0 fonctionner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et dans tous les cas, ces PSD sont, au fond, vraiment innocents - ils sont n\u00e9s d'un besoin d'autoprotection. Ils sont le r\u00e9sultat de situations toxiques dans le pass\u00e9, dans lesquelles cette personne s'est trouv\u00e9e. O\u00f9 leur comportement autodestructeur (SDB) les a soulag\u00e9s. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imaginons par exemple que N. ait eu une relation toxique avec son p\u00e8re, qui \u00e9tait peut-\u00eatre hypercritique, froid et peut-\u00eatre narcissique. Ne serait-il pas normal qu'elle s'\u00e9loigne de lui autant que possible ? Ne pas partager les d\u00e9tails personnels, afin de r\u00e9duire la surface d'attaque ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui fonctionnait auparavant la punit maintenant, elle et son entourage. C'est \u00e0 elle de r\u00e9soudre ce probl\u00e8me, peut-\u00eatre avec l'aide d'un th\u00e9rapeute. J'esp\u00e8re sinc\u00e8rement qu'elle parviendra \u00e0 le r\u00e9soudre, car je l'aime vraiment beaucoup. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais j'ai cess\u00e9 de payer son prix pour elle. Je ne peux rien faire de mon c\u00f4t\u00e9 - l'accepter ne ferait qu'accro\u00eetre la souffrance de mon c\u00f4t\u00e9. Je me suis d\u00e9sengag\u00e9 d'elle. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Employ\u00e9s et coll\u00e8gues<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Deux autres exemples me viennent \u00e0 l'esprit, des ex-employ\u00e9s que j'avais embauch\u00e9s. En tant que manager\/propri\u00e9taire, j'ai le luxe de pouvoir laisser partir les personnes qui se pr\u00e9sentent avec un lourd \"prix\" \u00e0 payer pour l'entreprise. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">F.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">F. m'a racont\u00e9 comment sa voiture avait \u00e9t\u00e9 ray\u00e9e par des coll\u00e8gues, en repr\u00e9sailles. C'est la seule personne que j'ai laiss\u00e9 partir apr\u00e8s seulement trois jours de travail avec nous. J'ai compris qu'il \u00e9tait anim\u00e9 par le d\u00e9sir d'avoir le plus de pouvoir possible, un pouvoir sur les autres. S'il devait rabaisser les autres, \u00eatre peu coop\u00e9ratif et montrer qu'il \u00e9tait en quelque sorte sup\u00e9rieur aux autres, pour obtenir ce sentiment de pouvoir, il le ferait. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il avait persist\u00e9 pendant dix ans sur son pr\u00e9c\u00e9dent lieu de travail, si je me souviens bien, jusqu'\u00e0 l'arriv\u00e9e d'un nouveau type qui ne supportait pas sa fa\u00e7on de contr\u00f4ler les gens. Qui l'a menac\u00e9 - alors F. a d\u00e9missionn\u00e9 de lui-m\u00eame. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9alisant qu'il y aurait <strong>friction constante <\/strong>avec F - par exemple, il ne permettait pas \u00e0 ma coll\u00e8gue S. de lui montrer les ficelles du m\u00e9tier, ne suivait pas ses instructions (pour montrer sa \"sup\u00e9riorit\u00e9\"), j'ai fait ce qu'il fallait en tant que manager.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J'ai arr\u00eat\u00e9 de payer les prix de F. - et je l'ai laiss\u00e9 payer ses prix lui-m\u00eame. Je l'ai laiss\u00e9 partir. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peut-\u00eatre que F. r\u00e9alisera qu'il s'ostracise lui-m\u00eame. Peut-\u00eatre pas. Le plus probable est que cela prendra plus d'it\u00e9rations, ou qu'il finira dans une entreprise o\u00f9 le patron aura plus de mal \u00e0 laisser partir F. - non pas parce que ce ne serait pas le bon choix, mais parce qu'il a peur de laisser partir les gens et qu'il n'a pas d'exp\u00e9rience dans ce domaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cette histoire r\u00e9sonne-t-elle en vous ? Peut-\u00eatre \u00eates-vous dans une relation toxique, o\u00f9 votre partenaire vous rabaisse ? Continuez vous \u00e0 payer le prix de votre partenaire ? En fait, son comportement devrait rebuter les autres et il devrait \u00eatre ostracis\u00e9 en retour ?<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">G.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il s'agit d'une autre employ\u00e9e qui \u00e9tait avec nous depuis quatre mois. Elle a \u00e9t\u00e9 malade pendant environ 50 % de cette p\u00e9riode. Corona au d\u00e9but - mais un simple rhume par la suite. Et ses performances dans d'autres domaines n'\u00e9taient pas \u00e0 la hauteur de nos normes. Alors qu'elle \u00e9tait en cong\u00e9 de maladie, que l'entreprise manquait cruellement de personnel et que mon coll\u00e8gue A. devait assumer la plus grande partie du travail, G. a demand\u00e9 \u00e0 l'avance deux jours de cong\u00e9 suppl\u00e9mentaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D'une certaine mani\u00e8re, G. ne prenait pas la responsabilit\u00e9 de faire partie de l'entreprise et d'y contribuer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne s'agit pas de pouvoir pour elle. Peut-\u00eatre s'agit-il de la peur de faire des erreurs, peut-\u00eatre de la peur de poser des questions \/ de communiquer \/ de r\u00e9fl\u00e9chir aux besoins des autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quoi qu'il en soit, je me rends compte que j'ai sur les bras une employ\u00e9e dont le rendement est inf\u00e9rieur aux attentes - lorsqu'elle est pr\u00e9sente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous manquons de personnel, mais quand m\u00eame, investir de l'argent dans quelqu'un qui ne se pr\u00e9sente pas \u00e0 100 %, m\u00eame quand elle est au travail... <strong>payerait ses prix<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que manager, je dois prendre les bonnes d\u00e9cisions pour mon entreprise. Et vous aussi, en tant que manager de votre vie, vous devez prendre les bonnes d\u00e9cisions pour votre vie. <strong>Arr\u00eatez de payer les prix des autres<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lieu de travail toxique ? Des coll\u00e8gues toxiques ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates vous-m\u00eame employ\u00e9 et que vous avez des coll\u00e8gues toxiques, je vous recommande d'arr\u00eater de payer leur prix - ne couvrez pas les brutes, par exemple - et si la direction ne fait rien, c'est que vous avez malheureusement une culture de travail toxique. Partez ! <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arr\u00eatez de gaspiller ces ann\u00e9es de vie \u00e0 payer les prix des autres, mon ami.<\/strong>. Fixez des limites solides - peut-\u00eatre qu'ils comprendront, peut-\u00eatre qu'ils ne comprendront pas.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces prix ne sont pas \u00e0 votre charge, ils sont \u00e0 la leur. Et finalement, peut-\u00eatre, le prix \u00e0 payer sera si \u00e9lev\u00e9 qu'ils ne pourront plus fermer les yeux et commenceront \u00e0 travailler avec un th\u00e9rapeute ou par d'autres moyens. Ils deviendront sobres et cesseront de d\u00e9truire leur foie et leur vie. Alors, ils seront pr\u00eats \u00e0 \u00eatre un partenaire possible pour vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Photo par <a href=\"https:\/\/unsplash.com\/ja\/@jontyson?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Jon Tyson<\/a> sur <a href=\"https:\/\/unsplash.com\/photos\/2TzSuQZOHe4?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Unsplash<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>When you go shopping with your friends, do you pay for their groceries? Maybe once in a while, but not all the time, right? Sometimes we end up &#8220;paying for the groceries&#8221; for important people in our lives. And someone who doesn&#8217;t pay for the groceries themselves will not see their value as directly and [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17,10],"tags":[157,156,18,71],"class_list":["post-336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boundaries","category-self-defeating-behaviors","tag-alcoholic","tag-others-prices","tag-prices","tag-sdb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Don&#039;t pay prices other people should be paying - VitalMeaning<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vitalmeaning.com\/fr\/ne-pas-payer-les-prix-que-dautres-devraient-payer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Don&#039;t pay prices other people should be paying - VitalMeaning\" \/>\n<meta property=\"og:description\" content=\"When you go shopping with your friends, do you pay for their groceries? Maybe once in a while, but not all the time, right? Sometimes we end up &#8220;paying for the groceries&#8221; for important people in our lives. And someone who doesn&#8217;t pay for the groceries themselves will not see their value as directly and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vitalmeaning.com\/fr\/ne-pas-payer-les-prix-que-dautres-devraient-payer\/\" \/>\n<meta property=\"og:site_name\" content=\"VitalMeaning\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-05T06:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-05T06:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Max\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Max\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/\"},\"author\":{\"name\":\"Max\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\"},\"headline\":\"Don&#8217;t pay prices other people should be paying\",\"datePublished\":\"2023-03-05T06:21:56+00:00\",\"dateModified\":\"2023-03-05T06:21:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/\"},\"wordCount\":1665,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vitalmeaning.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg\",\"keywords\":[\"alcoholic\",\"other&#039;s prices\",\"prices\",\"sdb\"],\"articleSection\":[\"boundaries\",\"self defeating behaviors\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/\",\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/\",\"name\":\"Don't pay prices other people should be paying - VitalMeaning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vitalmeaning.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg\",\"datePublished\":\"2023-03-05T06:21:56+00:00\",\"dateModified\":\"2023-03-05T06:21:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vitalmeaning.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg\",\"width\":640,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/dont-pay-prices-other-people-should-be-paying\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vitalmeaning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Don&#8217;t pay prices other people should be paying\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#website\",\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/\",\"name\":\"VitalMeaning\",\"description\":\"my self development journey\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vitalmeaning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vitalmeaning.com\\\/#\\\/schema\\\/person\\\/c2f46184a8199a4eeb7d1ed7ea80bcff\",\"name\":\"Max\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g\",\"caption\":\"Max\"},\"description\":\"I am an entrepreneur with an eclectic background. Currently into Raspberry Pi, Artificial Intelligence, and Personal Development. A big fan of Thais Gibson and her YouTube channel &amp; school :-)\",\"sameAs\":[\"https:\\\/\\\/pi3g.com\"],\"url\":\"https:\\\/\\\/vitalmeaning.com\\\/fr\\\/author\\\/max\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ne payez pas les prix que les autres devraient payer - VitalMeaning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vitalmeaning.com\/fr\/ne-pas-payer-les-prix-que-dautres-devraient-payer\/","og_locale":"fr_FR","og_type":"article","og_title":"Don't pay prices other people should be paying - VitalMeaning","og_description":"When you go shopping with your friends, do you pay for their groceries? Maybe once in a while, but not all the time, right? Sometimes we end up &#8220;paying for the groceries&#8221; for important people in our lives. And someone who doesn&#8217;t pay for the groceries themselves will not see their value as directly and [&hellip;]","og_url":"https:\/\/vitalmeaning.com\/fr\/ne-pas-payer-les-prix-que-dautres-devraient-payer\/","og_site_name":"VitalMeaning","article_published_time":"2023-03-05T06:21:56+00:00","article_modified_time":"2023-03-05T06:21:57+00:00","og_image":[{"width":640,"height":853,"url":"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg","type":"image\/jpeg"}],"author":"Max","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Max","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#article","isPartOf":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/"},"author":{"name":"Max","@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff"},"headline":"Don&#8217;t pay prices other people should be paying","datePublished":"2023-03-05T06:21:56+00:00","dateModified":"2023-03-05T06:21:57+00:00","mainEntityOfPage":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/"},"wordCount":1665,"commentCount":1,"image":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#primaryimage"},"thumbnailUrl":"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg","keywords":["alcoholic","other&#039;s prices","prices","sdb"],"articleSection":["boundaries","self defeating behaviors"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/","url":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/","name":"Ne payez pas les prix que les autres devraient payer - VitalMeaning","isPartOf":{"@id":"https:\/\/vitalmeaning.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#primaryimage"},"image":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#primaryimage"},"thumbnailUrl":"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg","datePublished":"2023-03-05T06:21:56+00:00","dateModified":"2023-03-05T06:21:57+00:00","author":{"@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff"},"breadcrumb":{"@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#primaryimage","url":"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg","contentUrl":"https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg","width":640,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/vitalmeaning.com\/dont-pay-prices-other-people-should-be-paying\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vitalmeaning.com\/"},{"@type":"ListItem","position":2,"name":"Don&#8217;t pay prices other people should be paying"}]},{"@type":"WebSite","@id":"https:\/\/vitalmeaning.com\/#website","url":"https:\/\/vitalmeaning.com\/","name":"VitalMeaning","description":"mon parcours de d\u00e9veloppement personnel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vitalmeaning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/vitalmeaning.com\/#\/schema\/person\/c2f46184a8199a4eeb7d1ed7ea80bcff","name":"Max","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35d6f244e4222d36532072edf6643c9aa3041034ace4369ed44df8e2b70928f3?s=96&d=mm&r=g","caption":"Max"},"description":"Je suis un entrepreneur avec un parcours \u00e9clectique. Je m'int\u00e9resse actuellement au Raspberry Pi, \u00e0 l'intelligence artificielle et au d\u00e9veloppement personnel. Je suis un grand fan de Thais Gibson, de sa cha\u00eene YouTube et de son \u00e9cole :-)","sameAs":["https:\/\/pi3g.com"],"url":"https:\/\/vitalmeaning.com\/fr\/author\/max\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg",640,853,false],"thumbnail":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1-150x150.jpg",150,150,true],"medium":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1-225x300.jpg",225,300,true],"medium_large":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg",640,853,false],"large":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg",640,853,false],"1536x1536":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg",640,853,false],"2048x2048":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1.jpg",640,853,false],"trp-custom-language-flag":["https:\/\/vitalmeaning.com\/wp-content\/uploads\/2023\/03\/jon-tyson-2TzSuQZOHe4-unsplash-1-9x12.jpg",9,12,true]},"uagb_author_info":{"display_name":"Max","author_link":"https:\/\/vitalmeaning.com\/fr\/author\/max\/"},"uagb_comment_info":1,"uagb_excerpt":"When you go shopping with your friends, do you pay for their groceries? Maybe once in a while, but not all the time, right? Sometimes we end up &#8220;paying for the groceries&#8221; for important people in our lives. And someone who doesn&#8217;t pay for the groceries themselves will not see their value as directly and\u2026","_links":{"self":[{"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/posts\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":1,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/posts\/336\/revisions"}],"predecessor-version":[{"id":338,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/posts\/336\/revisions\/338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/media\/337"}],"wp:attachment":[{"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/categories?post=336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vitalmeaning.com\/fr\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}